{"id":4596,"date":"2021-05-07T15:51:44","date_gmt":"2021-05-07T13:51:44","guid":{"rendered":"https:\/\/www.clinrealonline.fr\/about\/"},"modified":"2025-05-07T13:05:49","modified_gmt":"2025-05-07T11:05:49","slug":"a-proposito","status":"publish","type":"page","link":"https:\/\/www.clinrealonline.fr\/es\/a-proposito\/","title":{"rendered":"A prop\u00f3sito"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=\u00bb3\/12&#8243;][\/vc_column][vc_column width=\u00bb6\/12&#8243;]    <div class=\"clinreal-title \">\n        <h1><span class=\"SquareTitle\">A prop\u00f3sito de ClinReal <\/span><br\/><span><\/span><\/h1>\n    <\/div>\n    [vc_empty_space][vc_column_text css=\u00bb\u00bb el_class=\u00bbintro\u00bb]Es una sociedad de tama\u00f1o humano, innovadora e independiente. CLINREAL es una empresa tolosana que cuenta con 15 empleados, especializada en servicios de investigaci\u00f3n en Dermocosmetolog\u00eda. En la actualidad, CLINREAL acompa\u00f1a a laboratorios Dermocosm\u00e9ticos en la gesti\u00f3n de Cosmetovigilancia e Investigaci\u00f3n cl\u00ednica.[\/vc_column_text][\/vc_column][vc_column width=\u00bb3\/12&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/3&#8243;][vc_empty_space height=\u00bb120px\u00bb]    <div class=\"clinreal-sous-titre \">\n        <h2>\n            <span class=\"sb  \">La g\u00e9nesis<\/span>\n        \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space][vc_column_text el_class=\u00bbgotham text-gris\u00bb]<\/p>\n<h3><strong>La historia de un vanguardista en investigaci\u00f3n cl\u00ednica<\/strong><\/h3>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text css=\u00bb\u00bb]\u00c9rase una vez <strong>Bernard Chadoutaud, <\/strong>Biof\u00edsico diplomado en Ingenier\u00eda Biol\u00f3gica y Medical. En 1983, crea el laboratorio de <b>Biometrolog\u00eda\u00a0<\/b>cut\u00e1nea en el centro de I&amp;D de un importante Laboratorio Dermatol\u00f3gico y Cosmetol\u00f3gico.En 1989 es co-fundador y director general de la sociedad A2C Cosmetologie, la cu\u00e1l se clasifica en 1991 dentro de las 150 primeras PMI de alta tecnolog\u00eda de Francia. Desde 1995, como consultante, se encarga de misiones de auditoria t\u00e9cnica y consejos cient\u00edficos a nivel europeo. 10 a\u00f1os m\u00e1s tarde, a ra\u00edz de su encuentro con Philippe Rossard, y sumado a los a\u00f1os dedicados a la investigaci\u00f3n cl\u00ednica, fundan en conjunto CLINREAL ONLINE con la voluntad de desarrollar un\u00a0<b>m\u00e9todo innovador\u00a0<\/b>basado en la observaci\u00f3n de lo real con una forma de trabajo a\u00fan desconocida, el teletrabajo.[\/vc_column_text][vc_empty_space height=\u00bb120px\u00bb][\/vc_column][vc_column width=\u00bb2\/3&#8243;]\n\t\t\t<!-- START Timeline ES REVOLUTION SLIDER 6.7.40 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_7_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_7_1\" style=\"\" data-version=\"6.7.40\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-38\" data-title=\"2005-2008\" data-in=\"o:0;y:100%;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"2005-2008\" title=\"A prop\u00f3sito\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:100%;h:6px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;background-color:#cd897d;\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-597px;y:426px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:48px;h:48px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"48\" height=\"48\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Ellipse-29@2x.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#1d1d1b\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-383px;y:607px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:247px;h:145px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'Open Sans';\"\n\t\t\t\t\t\t\t>Creaci\u00f3n de la empresa CLINREAL ONLINE en Investigaci\u00f3n Cl\u00ednica con el TCO: Test Cl\u00ednico Observacional bajo control medical \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:1px;y:254px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:59px;h:149px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"59\" height=\"149\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/2006.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:435px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:32px;h:32px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"32\" height=\"32\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Ellipse-27-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-6\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:465px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:6px;h:137px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"6\" height=\"137\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Rectangle-76.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-7\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#1d1d1b\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:607px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:247px;h:145px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'Open Sans';\"\n\t\t\t\t\t\t\t>Precursor de una organizaci\u00f3n innovadora en teletrabajo \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-8\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:399px;y:255px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:59px;h:147px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"59\" height=\"147\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/2008.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-9\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:399px;y:435px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:32px;h:32px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"32\" height=\"32\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Ellipse-27-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-10\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:399px;y:465px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:6px;h:137px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"6\" height=\"137\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Rectangle-76.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-11\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#1d1d1b\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:400px;y:607px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:247px;h:145px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'Open Sans';\"\n\t\t\t\t\t\t\t>Lanzamiento del departamento de Cosmetovigilancia<br \/>\nCreaci\u00f3n del m\u00e9todo QCMvigilance\u00ae \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-13\" \n\t\t\t\t\t\t\t\tdata-type=\"object\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:50px;y:50px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Roboto';\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-15\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-384px;y:435px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:32px;h:32px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"32\" height=\"32\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Ellipse-27-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-16\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-384px;y:465px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:6px;h:137px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"6\" height=\"137\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Rectangle-76.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-38-layer-18\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:206px;y:255px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:59px;h:147px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"59\" height=\"147\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/2005.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-37\" data-title=\"2013-2021\" data-in=\"o:0;y:100%;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"2013-2021\" title=\"A prop\u00f3sito\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:100%;h:6px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;background-color:#cd897d;\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:r;y:426px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:48px;h:48px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"48\" height=\"48\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Ellipse-29@2x.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#1d1d1b\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-383px;y:607px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:247px;h:145px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'Open Sans';\"\n\t\t\t\t\t\t\t>Reglamento europeo sobre la Cosmetovigilancia \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:255px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:59px;h:147px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"59\" height=\"147\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/2020.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:435px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:32px;h:32px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"32\" height=\"32\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Ellipse-27-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-6\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:465px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:6px;h:137px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"6\" height=\"137\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Rectangle-76.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-7\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#1d1d1b\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:607px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:247px;h:145px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'Open Sans';\"\n\t\t\t\t\t\t\t>Apertura de las oficinas en coworking<br \/>\nCLINREAL ONLINE se convierte en CLINREAL \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-8\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:399px;y:255px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:59px;h:130px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"59\" height=\"130\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/2021.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-9\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:399px;y:435px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:32px;h:32px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"32\" height=\"32\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Ellipse-27-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-10\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:399px;y:465px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:6px;h:137px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"6\" height=\"137\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Rectangle-76.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-11\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#1d1d1b\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:399px;y:607px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:247px;h:145px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'Open Sans';\"\n\t\t\t\t\t\t\t>Digitalizaci\u00f3n de QCMvigilance\u00ae \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-13\" \n\t\t\t\t\t\t\t\tdata-type=\"object\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:50px;y:50px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Roboto';\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-15\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-384px;y:435px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:32px;h:32px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"32\" height=\"32\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Ellipse-27-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-16\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-384px;y:465px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:6px;h:137px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"6\" height=\"137\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Rectangle-76.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-7-slide-37-layer-18\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:206px;y:255px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:59px;h:130px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.clinrealonline.fr\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"59\" height=\"130\" data-lazyload=\"\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/2013.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_7_1',rl:[1240,1024,778,480],el:[900],gw:[1240],gh:[900],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider71\"]!==undefined) {window.RS_MODULES.modules[\"revslider71\"].once = false;window.revapi7 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n[\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_empty_space height=\u00bb120px\u00bb]    <div class=\"clinreal-sous-titre \">\n        <h2>\n            <span class=\"sb  \">Nuestra misi\u00f3n<\/span>\n        \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space][vc_column_text el_class=\u00bbgotham text-gris\u00bb]<\/p>\n<h3>Volver el subjetivo en objetivo<\/h3>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text]CLINREAL moviliza sus conocimientos principalmente en el mercado europeo de la cosm\u00e9tica y de la nutraceutica.[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=\u00bb1\/2&#8243;][\/vc_column][\/vc_row][vc_row equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb][vc_column width=\u00bb1\/12&#8243;][vc_single_image image=\u00bb256&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space][\/vc_column][vc_column width=\u00bb5\/12&#8243;][vc_column_text el_class=\u00bbgotham text-rose\u00bb]<\/p>\n<h3><strong>Comprobar<\/strong><\/h3>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text css=\u00bb\u00bb el_class=\u00bbtext-rose\u00bb]que las alegaciones est\u00e9n conformes a la promesa marketing antes y despu\u00e9s del lanzamiento[\/vc_column_text][vc_column_text]Es la <strong><a href=\"https:\/\/www.clinrealonline.fr\/es\/recherche-clinique\/\"><span class=\"underline\">Investigaci\u00f3n cl\u00ednica<\/span><\/a><\/strong>[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=\u00bb1\/12&#8243;][vc_single_image image=\u00bb255&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space][\/vc_column][vc_column width=\u00bb5\/12&#8243;][vc_column_text el_class=\u00bbgotham text-rose\u00bb]<\/p>\n<h3><strong>Analizar<\/strong><\/h3>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text css=\u00bb\u00bb el_class=\u00bbtext-rose\u00bb]los efectos adversos despu\u00e9s de la comercializaci\u00f3n, con la voluntad de reivindicar la reconquista de la satisfacci\u00f3n del consumidor.[\/vc_column_text][vc_column_text]Es la <a href=\"https:\/\/www.clinrealonline.fr\/es\/clinreal-partenaire-prestataire-cosmetovigilance\/\"><strong><span class=\"underline\">Cosmetovigilancia<\/span><\/strong><\/a>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row full_width=\u00bbstretch_row_content_no_spaces\u00bb content_placement=\u00bbbottom\u00bb][vc_column width=\u00bb2\/3&#8243;][vc_empty_space][vc_single_image image=\u00bb151&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeInLeft\u00bb][vc_empty_space][\/vc_column][vc_column css_animation=\u00bbfadeInRightBig\u00bb width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1623844249779{padding-right: 250px !important;padding-left: 15px !important;}\u00bb el_class=\u00bbfullMob\u00bb][vc_empty_space height=\u00bb100px\u00bb][vc_column_text el_class=\u00bbtext-rose\u00bb]<strong>Ma\u00f1ana,<\/strong><strong><br \/>\nCLINREAL<\/strong>[\/vc_column_text][vc_column_text css=\u00bb\u00bb]progresar\u00e1 en sus objetivos gracias al an\u00e1lisis de nuevos datos y a las nuevas tecnolog\u00edas para objetivar los resultados y enriquecer sus conocimientos.[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=\u00bbstretch_row\u00bb el_class=\u00bbformeLeft\u00bb][vc_column][vc_empty_space height=\u00bb120px\u00bb]    <div class=\"clinreal-sous-titre \">\n        <h2>\n            <span class=\"sb  \">Valores que cuentan<\/span>\n        \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space][vc_row_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text el_class=\u00bbgotham text-gris\u00bb]<\/p>\n<h4>CREATIVOS<\/h4>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text css=\u00bb\u00bb]Como imaginar protocolos de investigaci\u00f3n a medida y buscar soluciones para todas las problem\u00e1ticas, inclusive las m\u00e1s complejas.[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text el_class=\u00bbgotham text-gris\u00bb]<\/p>\n<h4>DEDICADOS<\/h4>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text css=\u00bb\u00bb]C\u00f3mo crear una verdadera alianza para conseguir lo mejor de una relaci\u00f3n de confianza establecida desde el inicio del proyecto.[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text el_class=\u00bbgotham text-gris\u00bb]<\/p>\n<h4>AMBICIOSO<\/h4>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text css=\u00bb\u00bb]C\u00f3mo progresar juntos, mejorando continuamente en nuestros \u00e1mbitos respectivos.[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb2\/3&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_empty_space height=\u00bb80px\u00bb]    <div class=\"clinreal-sous-titre \">\n        <h2>\n            <span class=\"sb  withTitletwo \">CLINREAL<\/span>\n        <br\/> <span class=\"titre-deux\">se compromete en <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space][vc_column_text el_class=\u00bbtext-rose\u00bb]GARANTIA SOBRE LAS ALEGACIONES[\/vc_column_text][vc_column_text css=\u00bb\u00bb]CLINREAL compromete su profesionalismo y su palabra sobre los an\u00e1lisis formulados con honestidad y pugnacidad.[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text el_class=\u00bbtext-rose\u00bb]AL SERVICIO DE SUS AMBICIONES[\/vc_column_text][vc_column_text css=\u00bb\u00bb]CLINREAL se compromete en acompa\u00f1ar a las marcas dermocosm\u00e9ticas hacia el cero defecto y en reconquistar la satisfacci\u00f3n del consumidor final.[\/vc_column_text][vc_empty_space height=\u00bb80px\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u00bb80px\u00bb]    <div class=\"clinreal-sous-titre \">\n        <h2>\n            <span class=\"sb  \">Equipo<\/span>\n        \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb572&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Alessandra<\/span>\n        <br\/> <span class=\"titre-deux\">DETHIEUX <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text]Encargada de encuesta \u2013 Asistente Manager[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb574&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Armelle<\/span>\n        <br\/> <span class=\"titre-deux\">GARCIA <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text]Jefa de proyecto \u2013 Analista data[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb575&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Bernard<\/span>\n        <br\/> <span class=\"titre-deux\">CHADOUTAUD <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text]Gerente \u2013\u00a0 Director Cient\u00edfico[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb577&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Claire<\/span>\n        <br\/> <span class=\"titre-deux\">MAYLIE <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text]Jefa de Departamento \u2013 Farmac\u00e9utica cosmetovigilante[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb5186&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Marie<\/span>\n        <br\/> <span class=\"titre-deux\">BOYER <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text]Encargada de encuesta[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb576&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Marie-Christelle<\/span>\n        <br\/> <span class=\"titre-deux\">VALDIGUIE <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text]Asistente Manager[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb582&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Pauline<\/span>\n        <br\/> <span class=\"titre-deux\">JAULIN <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text]Encargada de encuesta \u2013 Encargada de comunicaci\u00f3n[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb589&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Philippe<\/span>\n        <br\/> <span class=\"titre-deux\">ROSSARD <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text]Adjunto del Gerente \u2013 DPD[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb580&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Laure<\/span>\n        <br\/> <span class=\"titre-deux\">SOUBRIE <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text css=\u00bb\u00bb]Encargada de encuesta[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb573&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Andressa<\/span>\n        <br\/> <span class=\"titre-deux\">BARTHOLDY <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text]Survey Operator \u2013 Manager Assistant[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb5290&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb css=\u00bb\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Sandra<\/span>\n        <br\/> <span class=\"titre-deux\">ATLANI <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text css=\u00bb\u00bb]Encargada de encuesta[\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][vc_single_image image=\u00bb5224&#8243; img_size=\u00bb276&#215;183&#8243; alignment=\u00bbcenter\u00bb css_animation=\u00bbfadeIn\u00bb css=\u00bb\u00bb][vc_empty_space height=\u00bb20px\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;]    <div class=\"clinreal-sous-titre text-gris\">\n        <h2>\n            <span class=\"sb  withTitletwo \">Sylvain<\/span>\n        <br\/> <span class=\"titre-deux\">REBERGA <\/span> \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space height=\u00bb20px\u00bb][vc_column_text]Director Medical[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row disable_element=\u00bbyes\u00bb][vc_column][vc_empty_space]    <div class=\"clinreal-sous-titre floatRight\">\n        <h2>\n            <span class=\"sb  \">Ils nous font confiance<\/span>\n        \t\t        <\/h2>\n\n\n    <\/div>\n    [vc_empty_space][vc_column_text]\n\t\t<style>\n\t\t\t#wpls-logo-showcase-slider-1 .wpls-fix-box,\n\t\t\t#wpls-logo-showcase-slider-1 .wpls-fix-box img.wp-post-image{max-height:250px; }\n\t\t<\/style>\n\n\t\t<div class=\"wpls-wrap wpls-logo-showcase-slider-wrp wpls-logo-clearfix wpls-design-1 \" data-conf=\"{&quot;slides_column&quot;:&quot;5&quot;,&quot;slides_scroll&quot;:1,&quot;dots&quot;:&quot;false&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;autoplay_interval&quot;:3000,&quot;loop&quot;:&quot;true&quot;,&quot;rtl&quot;:&quot;false&quot;,&quot;speed&quot;:800,&quot;center_mode&quot;:&quot;false&quot;,&quot;lazyload&quot;:&quot;&quot;}\">\n\t\t\t<div class=\"wpls-logo-showcase logo_showcase wpls-logo-slider  sliderimage_hide_border wpls-dots-false\" id=\"wpls-logo-showcase-slider-1\" >\n\t\t\t\t<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/a_logo-vichy_og-image-1.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/iprad-1.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/LOGO_BERDOUES-1.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/Sisley_Paris_logo-1.svg\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/logo-nuxe-1.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/Logo-expanscience.svg-1.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/LOGO_CAUDALIE_PRUNE-1.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/06\/yves-rocher.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/07\/etatpur.jpeg\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/07\/uriage.jpg\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/07\/puig.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/07\/bio-beaute.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/07\/resultime.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/07\/labrosseetdupont.png\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/07\/valmont.jpg\" alt=\"\" \/>\n\t\t\t<\/div>\n\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t[\/vc_column_text][vc_empty_space height=\u00bb60px\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=\u00bb3\/12&#8243;][\/vc_column][vc_column width=\u00bb6\/12&#8243;][vc_empty_space][vc_column_text css=\u00bb\u00bb el_class=\u00bbintro\u00bb]Es una sociedad de tama\u00f1o humano, innovadora e independiente. CLINREAL es una empresa tolosana que cuenta con 15 empleados, especializada en servicios de investigaci\u00f3n en Dermocosmetolog\u00eda. En la actualidad, CLINREAL acompa\u00f1a a laboratorios Dermocosm\u00e9ticos en la gesti\u00f3n de Cosmetovigilancia e Investigaci\u00f3n cl\u00ednica.[\/vc_column_text][\/vc_column][vc_column width=\u00bb3\/12&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/3&#8243;][vc_empty_space height=\u00bb120px\u00bb][vc_empty_space][vc_column_text el_class=\u00bbgotham text-gris\u00bb] La historia de un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4596","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A prop\u00f3sito - ClinReal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clinrealonline.fr\/es\/a-proposito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A prop\u00f3sito - ClinReal\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column width=\u00bb3\/12&#8243;][\/vc_column][vc_column width=\u00bb6\/12&#8243;][vc_empty_space][vc_column_text css=\u00bb\u00bb el_class=\u00bbintro\u00bb]Es una sociedad de tama\u00f1o humano, innovadora e independiente. CLINREAL es una empresa tolosana que cuenta con 15 empleados, especializada en servicios de investigaci\u00f3n en Dermocosmetolog\u00eda. En la actualidad, CLINREAL acompa\u00f1a a laboratorios Dermocosm\u00e9ticos en la gesti\u00f3n de Cosmetovigilancia e Investigaci\u00f3n cl\u00ednica.[\/vc_column_text][\/vc_column][vc_column width=\u00bb3\/12&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/3&#8243;][vc_empty_space height=\u00bb120px\u00bb][vc_empty_space][vc_column_text el_class=\u00bbgotham text-gris\u00bb] La historia de un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clinrealonline.fr\/es\/a-proposito\/\" \/>\n<meta property=\"og:site_name\" content=\"ClinReal\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-07T11:05:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/a-proposito\\\/\",\"url\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/a-proposito\\\/\",\"name\":\"A prop\u00f3sito - ClinReal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/#website\"},\"datePublished\":\"2021-05-07T13:51:44+00:00\",\"dateModified\":\"2025-05-07T11:05:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/a-proposito\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/a-proposito\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/a-proposito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/clinreal-qcmvigilance-test-clinique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A prop\u00f3sito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/\",\"name\":\"ClinReal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/#organization\",\"name\":\"ClinReal\",\"url\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.clinrealonline.fr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Groupe-27.png\",\"contentUrl\":\"https:\\\/\\\/www.clinrealonline.fr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Groupe-27.png\",\"width\":161,\"height\":109,\"caption\":\"ClinReal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clinrealonline.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A prop\u00f3sito - ClinReal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clinrealonline.fr\/es\/a-proposito\/","og_locale":"es_ES","og_type":"article","og_title":"A prop\u00f3sito - ClinReal","og_description":"[vc_row][vc_column width=\u00bb3\/12&#8243;][\/vc_column][vc_column width=\u00bb6\/12&#8243;][vc_empty_space][vc_column_text css=\u00bb\u00bb el_class=\u00bbintro\u00bb]Es una sociedad de tama\u00f1o humano, innovadora e independiente. CLINREAL es una empresa tolosana que cuenta con 15 empleados, especializada en servicios de investigaci\u00f3n en Dermocosmetolog\u00eda. En la actualidad, CLINREAL acompa\u00f1a a laboratorios Dermocosm\u00e9ticos en la gesti\u00f3n de Cosmetovigilancia e Investigaci\u00f3n cl\u00ednica.[\/vc_column_text][\/vc_column][vc_column width=\u00bb3\/12&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/3&#8243;][vc_empty_space height=\u00bb120px\u00bb][vc_empty_space][vc_column_text el_class=\u00bbgotham text-gris\u00bb] La historia de un [&hellip;]","og_url":"https:\/\/www.clinrealonline.fr\/es\/a-proposito\/","og_site_name":"ClinReal","article_modified_time":"2025-05-07T11:05:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clinrealonline.fr\/es\/a-proposito\/","url":"https:\/\/www.clinrealonline.fr\/es\/a-proposito\/","name":"A prop\u00f3sito - ClinReal","isPartOf":{"@id":"https:\/\/www.clinrealonline.fr\/es\/#website"},"datePublished":"2021-05-07T13:51:44+00:00","dateModified":"2025-05-07T11:05:49+00:00","breadcrumb":{"@id":"https:\/\/www.clinrealonline.fr\/es\/a-proposito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clinrealonline.fr\/es\/a-proposito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.clinrealonline.fr\/es\/a-proposito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.clinrealonline.fr\/es\/clinreal-qcmvigilance-test-clinique\/"},{"@type":"ListItem","position":2,"name":"A prop\u00f3sito"}]},{"@type":"WebSite","@id":"https:\/\/www.clinrealonline.fr\/es\/#website","url":"https:\/\/www.clinrealonline.fr\/es\/","name":"ClinReal","description":"","publisher":{"@id":"https:\/\/www.clinrealonline.fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clinrealonline.fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.clinrealonline.fr\/es\/#organization","name":"ClinReal","url":"https:\/\/www.clinrealonline.fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinrealonline.fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Groupe-27.png","contentUrl":"https:\/\/www.clinrealonline.fr\/wp-content\/uploads\/2021\/05\/Groupe-27.png","width":161,"height":109,"caption":"ClinReal"},"image":{"@id":"https:\/\/www.clinrealonline.fr\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.clinrealonline.fr\/es\/wp-json\/wp\/v2\/pages\/4596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clinrealonline.fr\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.clinrealonline.fr\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.clinrealonline.fr\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clinrealonline.fr\/es\/wp-json\/wp\/v2\/comments?post=4596"}],"version-history":[{"count":20,"href":"https:\/\/www.clinrealonline.fr\/es\/wp-json\/wp\/v2\/pages\/4596\/revisions"}],"predecessor-version":[{"id":5638,"href":"https:\/\/www.clinrealonline.fr\/es\/wp-json\/wp\/v2\/pages\/4596\/revisions\/5638"}],"wp:attachment":[{"href":"https:\/\/www.clinrealonline.fr\/es\/wp-json\/wp\/v2\/media?parent=4596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}